{"id":11096,"date":"2024-08-24T19:30:59","date_gmt":"2024-08-24T19:30:59","guid":{"rendered":"https:\/\/eletrobrasinnovationgrid.com\/?page_id=11096"},"modified":"2025-12-12T13:46:45","modified_gmt":"2025-12-12T13:46:45","slug":"powerup-desafio-leitura-de-faturas-de-energia","status":"publish","type":"page","link":"https:\/\/eletrobrasinnovationgrid.com\/en\/powerup-desafio-leitura-de-faturas-de-energia\/","title":{"rendered":"PowerUp &#8211; Desafio &#8211; Leitura de faturas de energia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11096\" class=\"elementor elementor-11096\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d517b77 elementor-section-height-min-height ops-section she-header-yes elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7d517b77\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll&quot;:&quot;section&quot;,&quot;transparent&quot;:&quot;yes&quot;,&quot;transparent_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;scroll_distance&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:60,&quot;sizes&quot;:[]},&quot;scroll_distance_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;scroll_distance_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;she_offset_top_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;she_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:0,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:0,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b45cb61\" data-id=\"7b45cb61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e55a252 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"4e55a252\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\"\n\t\t\tdata-hamburger-icon=\"\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"1024\"\n\t\t\tdata-close-on-anchor=\"no\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                                    <span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span>\n                            <\/button>\n            <div id=\"ekit-megamenu-powerup\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-powerup\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-icon\"><li id=\"menu-item-9004\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-9004 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/eletrobrasinnovationgrid.com\/powerup\/#programa\" class=\"ekit-menu-nav-link\">Programa<\/a><\/li>\n<li id=\"menu-item-9005\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-9005 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/eletrobrasinnovationgrid.com\/powerup\/#desafios\" class=\"ekit-menu-nav-link\">Desafios<\/a><\/li>\n<li id=\"menu-item-9006\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-9006 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/eletrobrasinnovationgrid.com\/powerup\/#cronograma\" class=\"ekit-menu-nav-link\">Cronograma<\/a><\/li>\n<li id=\"menu-item-9007\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-9007 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/eletrobrasinnovationgrid.com\/powerup\/#participar\" class=\"ekit-menu-nav-link\">Por que participar<\/a><\/li>\n<li id=\"menu-item-9008\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-9008 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/eletrobrasinnovationgrid.com\/powerup\/#faq\" class=\"ekit-menu-nav-link\">F.A.Q.<\/a><\/li>\n<li id=\"menu-item-9009\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-9009 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/eletrobrasinnovationgrid.com\/powerup\/#sobre\" class=\"ekit-menu-nav-link\">Sobre<\/a><\/li>\n<li id=\"menu-item-9010\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-9010 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/eletrobrasinnovationgrid.com\/\" class=\"ekit-menu-nav-link\">Innovation Grid<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56418444 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"56418444\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18bb39d7\" data-id=\"18bb39d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4eba4c4d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4eba4c4d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-764db9e7\" data-id=\"764db9e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4606eae0 elementor-widget elementor-widget-heading\" data-id=\"4606eae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Leitura de faturas de energia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2952b8 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a2952b8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c1a7bd0\" data-id=\"c1a7bd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-748b919d elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"748b919d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"#desafioaberto\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-download-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Saiba mais sobre o desafio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a408bbc elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a408bbc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1c4433\" data-id=\"f1c4433\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68e1a6a elementor-widget elementor-widget-text-editor\" data-id=\"68e1a6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a style=\"color: #0072c6; text-decoration: none;\" href=\"https:\/\/eletrobrasinnovationgrid.com\/\">Home<\/a> &gt; <a style=\"color: #0072c6; text-decoration: none;\" href=\"https:\/\/eletrobrasinnovationgrid.com\/powerup\">PowerUp<\/a> &gt; <b>Desafio em andamento<\/b>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-973ec81 elementor-widget elementor-widget-menu-anchor\" data-id=\"973ec81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"desafioaberto\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-929da35 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"929da35\" data-element_type=\"section\" data-e-type=\"section\" id=\"suporte-ao-usuario\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-342c2cd\" data-id=\"342c2cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59581bf elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"59581bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-011bdcd\" data-id=\"011bdcd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc5bcb4 elementor-widget elementor-widget-heading\" data-id=\"fc5bcb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Automa\u00e7\u00e3o e escalabilidade na leitura de dados de faturas de energia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8f9ae8 elementor-widget elementor-widget-text-editor\" data-id=\"b8f9ae8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span class=\"NormalTextRun SpellingErrorV2Themed SCXW18082639 BCX8\">Sponsor<\/span><span class=\"NormalTextRun SCXW18082639 BCX8\">:<\/span><\/span> <a class=\"Hyperlink SCXW18082639 BCX8\" href=\"https:\/\/www.linkedin.com\/in\/patriciapaludo\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW18082639 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW18082639 BCX8\" data-ccp-charstyle=\"Hyperlink\">Patricia Rodrigues<\/span><\/span><\/a><span class=\"TextRun SCXW18082639 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW18082639 BCX8\">\u00a0\u00a0<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW18082639 BCX8\"><span class=\"SCXW18082639 BCX8\">\u00a0<\/span><br class=\"SCXW18082639 BCX8\" \/><\/span><span class=\"TextRun SCXW18082639 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW18082639 BCX8\">L\u00edder: <\/span><\/span><a class=\"Hyperlink SCXW18082639 BCX8\" href=\"https:\/\/www.linkedin.com\/in\/ana-lu%C3%ADsa-brito-fagundes-52a892140\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW18082639 BCX8\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW18082639 BCX8\" data-ccp-charstyle=\"Hyperlink\">Ana Luisa<\/span><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8228ac elementor-widget elementor-widget-heading\" data-id=\"d8228ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Como automatizar e escalar a extra\u00e7\u00e3o de dados de faturas de energia em diferentes formatos, incluindo imagens e arquivos sem padroniza\u00e7\u00e3o, reduzindo tempo de processamento e custos operacionais? <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9691fa elementor-widget elementor-widget-text-editor\" data-id=\"e9691fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"none\">Breve descri\u00e7\u00e3o:<\/span><\/b><span data-contrast=\"none\"> Atualmente, o processo de extra\u00e7\u00e3o de dados das faturas de energia demanda tempo e consider\u00e1veis recursos operacionais. Nosso objetivo \u00e9 tornar esse processo mais eficiente, reduzindo custos, diminuindo o tempo necess\u00e1rio e aprimorando a precis\u00e3o na leitura dos documentos.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Procuramos uma solu\u00e7\u00e3o que automatize a extra\u00e7\u00e3o de dados de faturas de energia de diferentes distribuidoras, permission\u00e1rias e concession\u00e1rias, independentemente do formato ou tipo de arquivo, como imagens e arquivos sem padroniza\u00e7\u00e3o. A solu\u00e7\u00e3o deve garantir mais de 95% de acur\u00e1cia na leitura, ser escal\u00e1vel para acompanhar o crescimento da empresa e integrar-se sem dificuldades aos sistemas existentes, incluindo o CRM Salesforce, com um custo unit\u00e1rio competitivo que assegure um excelente custo-benef\u00edcio.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60ee6bf elementor-widget elementor-widget-text-editor\" data-id=\"60ee6bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\"><b>Requisitos obrigat\u00f3rios para solu\u00e7\u00e3o do problema<\/b>\u00a0<br \/><\/span><\/p><p>1 &#8211; Leitura de todas as faturas de todas as distribuidoras, permission\u00e1rias e concession\u00e1rias (alta e baixa tens\u00e3o)\u00a0<span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">2 &#8211; Leitura de faturas em pdf estruturado\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">3 &#8211; Processamento e tabula\u00e7\u00e3o das informa\u00e7\u00f5es em menos de 1 minuto\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">4 &#8211; Processamento de faturas recebidas em tempo real\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">5 &#8211; Leitura de PDF e qualquer tipo de arquivo com acur\u00e1cia &gt;95%\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">6 &#8211; Capacidade de conex\u00e3o via API; recebimento dos dados e arquivo via API; integra\u00e7\u00e3o com sistemas existentes\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">7 &#8211; Recebimento do arquivo via e-mail\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">8 &#8211; Recebimento do arquivo via Landing page\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">9 &#8211; Retornar com os dados tabulados via excel, xml ou API\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">10 &#8211; Capacidade de leitura de no m\u00ednimo 500 faturas\/m\u00eas\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">11 &#8211; Capacidade de identifica\u00e7\u00e3o de altera\u00e7\u00e3o do nome dos campos\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">12 &#8211; Capacidade de tratamento dos dados (de\/para) para adequar os campos para utiliza\u00e7\u00e3o em outros sistemas\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">13 &#8211; Manuten\u00e7\u00e3o recorrente dos layouts de faturas j\u00e1 mapeadas\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">14 &#8211; Os dados coletados ser\u00e3o de controle exclusivo da AXIA Energia\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">15 &#8211; A solu\u00e7\u00e3o deve garantir a seguran\u00e7a e privacidade dos dados coletados da fatura do cliente.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Requisitos n\u00e3o funcionais (desej\u00e1veis)<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">1 &#8211; Interface com o usu\u00e1rio (site pr\u00f3prio)\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">2 &#8211; Que novos modelos de faturas sejam mapeados em at\u00e9 2 (dois) dias\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">3 &#8211; Rob\u00f4 para captura das informa\u00e7\u00f5es diretamente do site da distribuidora (condi\u00e7\u00e3o aplic\u00e1vel apenas para os clientes da AXIA Energia)\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\"><br \/><\/span><span data-contrast=\"none\">4 &#8211; Integra\u00e7\u00e3o com o CRM Salesforce\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f354c0b elementor-widget elementor-widget-text-editor\" data-id=\"f354c0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span class=\"NormalTextRun SCXW87729259 BCX8\">\u00a0<\/span><\/strong><b style=\"color: #007bff; font-weight: 400;\">Intelig\u00eancia Artificial<\/b>\u00a0| <b style=\"color: #007bff; font-weight: 400;\">Data Analytics<\/b> | <b style=\"color: #007bff; font-weight: 400;\">Automa\u00e7\u00e3o de Processos<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f672e8 elementor-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"8f672e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/eletrobras.aevoinnovate.net\/startup-area\/#\/confirm-email\/f8d53067-b498-4652-b030-511e9a7ae5da\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inscreva-se agora!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ee84e4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3ee84e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inscri\u00e7\u00f5es encerradas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e711965 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"e711965\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Etapas do programa<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-282dcd3 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"282dcd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"139\" src=\"https:\/\/eletrobrasinnovationgrid.com\/wp-content\/uploads\/2024\/04\/Frame-1-1024x139.png\" class=\"attachment-large size-large wp-image-10137\" alt=\"\" srcset=\"https:\/\/eletrobrasinnovationgrid.com\/wp-content\/uploads\/2024\/04\/Frame-1-1024x139.png 1024w, https:\/\/eletrobrasinnovationgrid.com\/wp-content\/uploads\/2024\/04\/Frame-1-300x41.png 300w, https:\/\/eletrobrasinnovationgrid.com\/wp-content\/uploads\/2024\/04\/Frame-1-768x104.png 768w, https:\/\/eletrobrasinnovationgrid.com\/wp-content\/uploads\/2024\/04\/Frame-1-18x2.png 18w, https:\/\/eletrobrasinnovationgrid.com\/wp-content\/uploads\/2024\/04\/Frame-1.png 1045w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Programa Desafios Cronograma Por que participar F.A.Q. Sobre Innovation Grid X Leitura de faturas de energia Saiba mais sobre o desafio Home &gt; PowerUp &gt; Desafio em andamento Automa\u00e7\u00e3o e escalabilidade na leitura de dados de faturas de energia Sponsor: Patricia Rodrigues\u00a0\u00a0\u00a0L\u00edder: Ana Luisa Como automatizar e escalar a extra\u00e7\u00e3o de dados de faturas de energia em diferentes formatos, incluindo imagens e arquivos sem padroniza\u00e7\u00e3o, reduzindo tempo de processamento e custos operacionais? Breve descri\u00e7\u00e3o: Atualmente, o processo de extra\u00e7\u00e3o de dados das faturas de energia demanda tempo e consider\u00e1veis recursos operacionais. Nosso objetivo \u00e9 tornar esse processo mais eficiente, reduzindo custos, diminuindo o tempo necess\u00e1rio e aprimorando a precis\u00e3o na leitura dos documentos.\u00a0 Procuramos uma solu\u00e7\u00e3o que automatize a extra\u00e7\u00e3o de dados de faturas de energia de diferentes distribuidoras, permission\u00e1rias e concession\u00e1rias, independentemente do formato ou tipo de arquivo, como imagens e arquivos sem padroniza\u00e7\u00e3o. A solu\u00e7\u00e3o deve garantir mais de 95% de acur\u00e1cia na leitura, ser escal\u00e1vel para acompanhar o crescimento da empresa e integrar-se sem dificuldades aos sistemas existentes, incluindo o CRM Salesforce, com um custo unit\u00e1rio competitivo que assegure um excelente custo-benef\u00edcio.\u00a0 Requisitos obrigat\u00f3rios para solu\u00e7\u00e3o do problema\u00a0 1 &#8211; Leitura de todas as faturas de todas as distribuidoras, permission\u00e1rias e concession\u00e1rias (alta e baixa tens\u00e3o)\u00a02 &#8211; Leitura de faturas em pdf estruturado\u00a03 &#8211; Processamento e tabula\u00e7\u00e3o das informa\u00e7\u00f5es em menos de 1 minuto\u00a04 &#8211; Processamento de faturas recebidas em tempo real\u00a05 &#8211; Leitura de PDF e qualquer tipo de arquivo com acur\u00e1cia &gt;95%\u00a06 &#8211; Capacidade de conex\u00e3o via API; recebimento dos dados e arquivo via API; integra\u00e7\u00e3o com sistemas existentes\u00a07 &#8211; Recebimento do arquivo via e-mail\u00a08 &#8211; Recebimento do arquivo via Landing page\u00a09 &#8211; Retornar com os dados tabulados via excel, xml ou API\u00a010 &#8211; Capacidade de leitura de no m\u00ednimo 500 faturas\/m\u00eas\u00a011 &#8211; Capacidade de identifica\u00e7\u00e3o de altera\u00e7\u00e3o do nome dos campos\u00a012 &#8211; Capacidade de tratamento dos dados (de\/para) para adequar os campos para utiliza\u00e7\u00e3o em outros sistemas\u00a013 &#8211; Manuten\u00e7\u00e3o recorrente dos layouts de faturas j\u00e1 mapeadas\u00a014 &#8211; Os dados coletados ser\u00e3o de controle exclusivo da AXIA Energia\u00a015 &#8211; A solu\u00e7\u00e3o deve garantir a seguran\u00e7a e privacidade dos dados coletados da fatura do cliente.\u00a0\u00a0 Requisitos n\u00e3o funcionais (desej\u00e1veis)\u00a0 1 &#8211; Interface com o usu\u00e1rio (site pr\u00f3prio)\u00a02 &#8211; Que novos modelos de faturas sejam mapeados em at\u00e9 2 (dois) dias\u00a03 &#8211; Rob\u00f4 para captura das informa\u00e7\u00f5es diretamente do site da distribuidora (condi\u00e7\u00e3o aplic\u00e1vel apenas para os clientes da AXIA Energia)\u00a04 &#8211; Integra\u00e7\u00e3o com o CRM Salesforce\u00a0\u00a0 \u00a0Intelig\u00eancia Artificial\u00a0| Data Analytics | Automa\u00e7\u00e3o de Processos Inscreva-se agora! Inscri\u00e7\u00f5es encerradas Etapas do programa<\/p>","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-11096","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eletrobrasinnovationgrid.com\/en\/wp-json\/wp\/v2\/pages\/11096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eletrobrasinnovationgrid.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eletrobrasinnovationgrid.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eletrobrasinnovationgrid.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eletrobrasinnovationgrid.com\/en\/wp-json\/wp\/v2\/comments?post=11096"}],"version-history":[{"count":0,"href":"https:\/\/eletrobrasinnovationgrid.com\/en\/wp-json\/wp\/v2\/pages\/11096\/revisions"}],"wp:attachment":[{"href":"https:\/\/eletrobrasinnovationgrid.com\/en\/wp-json\/wp\/v2\/media?parent=11096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}